{"id":42615,"date":"2017-02-06T14:53:58","date_gmt":"2017-02-06T13:53:58","guid":{"rendered":"https:\/\/aquajet.se\/news\/aquajets-hydrodemolition-days-2017\/"},"modified":"2017-02-06T14:53:58","modified_gmt":"2017-02-06T13:53:58","slug":"aquajets-hydrodemolition-days-2017","status":"publish","type":"news","link":"https:\/\/aquajet.se\/de\/news\/aquajets-hydrodemolition-days-2017\/","title":{"rendered":"Aquajet&#8217;s Hydrodemolition Days 2017"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2612\" src=\"https:\/\/aquajet.se\/bed\/uploads\/2017\/02\/aquajet_hydrodemolitiondays2017_2.jpg\" alt=\"\" width=\"1600\" height=\"950\"><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Aquajet&#8217;s Hydrodemolition Tage <\/strong>5-6 von April 2017<\/h3>\n<p>Vielen Dank an alle, die sich die Zeit nehmen, uns bei unseren Hydrodemolition-Tagen zu begleiten!<br \/>\nEin herzliches Willkommen an Sie alle! Wir freuen uns, Sie hier zu haben. <\/p>\n<p>&nbsp;<\/p>\n<h3>Zeitplan f\u00fcr den<sup>5.<\/sup> und<sup>6.<\/sup> April<\/h3>\n<p><em><strong>Thema: Die Umwelt<\/strong><\/em><\/p>\n<p><strong>Mittwoch<sup>, 5.<\/sup> April<\/strong><\/p>\n<table cellpadding=\"5px\">\n<tbody>\n<tr>\n<td><strong>12.00<\/strong><\/td>\n<td>Begr\u00fc\u00dfung und Mittagessen im Aquajet<\/td>\n<\/tr>\n<tr>\n<td><strong>13.00<\/strong><\/td>\n<td>Roger Simonsson, unser Gesch\u00e4ftsf\u00fchrer, stellt das Thema der diesj\u00e4hrigen Veranstaltung vor, gefolgt von unserem Chefingenieur Ronnie Hilmersson, der \u00fcber unsere neuen Entwicklungen sprechen wird.<\/td>\n<\/tr>\n<tr>\n<td><strong>13.30<\/strong><\/td>\n<td>Herr David Porciello von Cor-Blast, Kanada, betritt die B\u00fchne und spricht \u00fcber Hydrodemolition aus der Sicht eines Bauunternehmers.<\/td>\n<\/tr>\n<tr>\n<td><strong>14.00<\/strong><\/td>\n<td>Live-Demonstration unseres Wasserfiltersystems, dem EcoClear 2.0 mit dem neuen intelligenten RECO-Steuerungssystem.<\/td>\n<\/tr>\n<tr>\n<td><strong>14.30<\/strong><\/td>\n<td>Vorf\u00fchrung von StoneAge-Produkten mit Andrew Birt von StoneAge.<br \/>\nEs werden auch Vertreter von TST Sweden AB ihre Sicherheitsausr\u00fcstung vorf\u00fchren.<\/td>\n<\/tr>\n<tr>\n<td><strong>15.00<\/strong><\/td>\n<td>Kaffeepause<\/td>\n<\/tr>\n<tr>\n<td><strong>15.30<\/strong><\/td>\n<td>Live-Demos unserer:<br \/>\nAqua Cutter 710V evolution 2.0 mit einem Power Pack EcoSilence.<br \/>\nAqua Cutter 410A evolution 2.0 mit einem Power Pack UHP.<\/td>\n<\/tr>\n<tr>\n<td><strong>17.00<\/strong><\/td>\n<td>Bus zur\u00fcck zum Hotel.<\/td>\n<\/tr>\n<tr>\n<td><strong>18.30<\/strong><\/td>\n<td>Ein Bus holt Sie ab und bringt Sie nach Wallby S\u00e4teri, einem bekannten Ferienort hier in Sm\u00e5land, Schweden. Dort werden wir ein gutes Abendessen und Unterhaltung genie\u00dfen. <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>Donnerstag,<sup>6.<\/sup> April<\/strong><\/p>\n<table cellpadding=\"5px\">\n<tbody>\n<tr>\n<td><strong>09.00<\/strong><\/td>\n<td>Zusammenfassung der gestrigen Erfahrungen und Zeit f\u00fcr Fragen und Antworten. Sie werden Gelegenheit f\u00fcr spezifischere Gespr\u00e4che und Produktpr\u00e4sentationen haben. <\/td>\n<\/tr>\n<tr>\n<td><strong>12.00<\/strong><\/td>\n<td>Mittagessen und Abschluss.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2609\" src=\"https:\/\/aquajet.se\/bed\/uploads\/2017\/02\/hydrodemolition_days_2017_1.jpg\" alt=\"\" width=\"1326\" height=\"868\"><\/p>\n<p>&nbsp;<\/p>\n<h3>Wie Sie zu Aquajet Systems in Holsbybrunn, Schweden reisen<\/h3>\n<p>Unsere Position ist N57\u00b025.966&#8242; E015\u00b012.038&#8242;<\/p>\n<p><iframe loading=\"lazy\" style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2147.6672022744997!2d15.198400852015137!3d57.43289876854058!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x46575f98d9306fcb%3A0x3c32456193c74c78!2sAquajet+Systems+AB!5e0!3m2!1ssv!2sse!4v1486389582929\" width=\"100%\" height=\"350\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Der einfachste Weg, um nach Holsbybrunn und zu Aquajet Systems AB zu kommen, ist ein Flug zum Flughafen Kopenhagen. Von dort aus k\u00f6nnen Sie eine direkte Zugverbindung nach N\u00e4ssj\u00f6 in Schweden nehmen, wo es einen Anschlusszug nach Vetlanda gibt, wo wir Sie abholen werden. Die Fahrt von Kopenhagen aus dauert etwa 2,5 Stunden. Es gibt auch einen Zug nach N\u00e4ssj\u00f6 vom Stockholmer Flughafen Arlanda. Die n\u00e4chstgelegenen Inlandsflugh\u00e4fen sind entweder V\u00e4xj\u00f6 oder J\u00f6nk\u00f6ping. Wir k\u00f6nnen Sie am Bahnhof oder an einem anderen Ort abholen.    <\/p>\n<p>Bitte z\u00f6gern Sie nicht, uns zu kontaktieren, wenn Sie irgendwelche Fragen haben.<\/p>\n<p>Willkommen zu unseren Hydrodemolition-Tagen 2017 bei Aquajet Systems AB.<\/p>\n<p>Wir hoffen, Sie hier zu sehen!<\/p>\n<p><strong><em><span style=\"color: #ff0000;\">\/\/<\/span> <\/em><em>Das Aquajet-Team<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aquajet&#8217;s Hydrodemolition Tage 5-6 von April 2017 Vielen Dank an alle, die sich die Zeit nehmen, uns bei unseren Hydrodemolition-Tagen zu begleiten! Ein herzliches Willkommen an Sie alle! Wir freuen uns, Sie hier zu haben. &nbsp; Zeitplan f\u00fcr den5. und6. April Thema: Die Umwelt Mittwoch, 5. April 12.00 Begr\u00fc\u00dfung und Mittagessen im Aquajet 13.00 [&hellip;]<\/p>\n","protected":false},"featured_media":19544,"template":"","news_type":[],"class_list":["post-42615","news","type-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.2 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aquajet&#039;s Hydrodemolition Days 2017 - Aquajet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aquajet.se\/de\/news\/aquajets-hydrodemolition-days-2017\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aquajet&#039;s Hydrodemolition Days 2017\" \/>\n<meta property=\"og:description\" content=\"Aquajet&#8217;s Hydrodemolition Tage 5-6 von April 2017 Vielen Dank an alle, die sich die Zeit nehmen, uns bei unseren Hydrodemolition-Tagen zu begleiten! Ein herzliches Willkommen an Sie alle! Wir freuen uns, Sie hier zu haben. &nbsp; Zeitplan f\u00fcr den5. und6. April Thema: Die Umwelt Mittwoch, 5. April 12.00 Begr\u00fc\u00dfung und Mittagessen im Aquajet 13.00 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aquajet.se\/de\/news\/aquajets-hydrodemolition-days-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Aquajet\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aquajet.se\/bed\/uploads\/2017\/02\/aquajet_hydrodemolitiondays2017-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aquajet.se\\\/de\\\/news\\\/aquajets-hydrodemolition-days-2017\\\/\",\"url\":\"https:\\\/\\\/aquajet.se\\\/de\\\/news\\\/aquajets-hydrodemolition-days-2017\\\/\",\"name\":\"Aquajet's Hydrodemolition Days 2017 - Aquajet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aquajet.se\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aquajet.se\\\/de\\\/news\\\/aquajets-hydrodemolition-days-2017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aquajet.se\\\/de\\\/news\\\/aquajets-hydrodemolition-days-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aquajet.se\\\/bed\\\/uploads\\\/2017\\\/02\\\/aquajet_hydrodemolitiondays2017-1.jpg\",\"datePublished\":\"2017-02-06T13:53:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aquajet.se\\\/de\\\/news\\\/aquajets-hydrodemolition-days-2017\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aquajet.se\\\/de\\\/news\\\/aquajets-hydrodemolition-days-2017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/aquajet.se\\\/de\\\/news\\\/aquajets-hydrodemolition-days-2017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aquajet.se\\\/bed\\\/uploads\\\/2017\\\/02\\\/aquajet_hydrodemolitiondays2017-1.jpg\",\"contentUrl\":\"https:\\\/\\\/aquajet.se\\\/bed\\\/uploads\\\/2017\\\/02\\\/aquajet_hydrodemolitiondays2017-1.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aquajet.se\\\/de\\\/news\\\/aquajets-hydrodemolition-days-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/aquajet.se\\\/de\\\/welcome-to-the-future-of-cutting-edge-hydrodemolition\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aquajet Nachrichten\",\"item\":\"https:\\\/\\\/aquajet.se\\\/de\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aquajet&#8217;s Hydrodemolition Days 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aquajet.se\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/aquajet.se\\\/de\\\/\",\"name\":\"Aquajet\",\"description\":\"Proven Hydrodemolition Equipment\",\"publisher\":{\"@id\":\"https:\\\/\\\/aquajet.se\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aquajet.se\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aquajet.se\\\/de\\\/#organization\",\"name\":\"Aquajet\",\"url\":\"https:\\\/\\\/aquajet.se\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/aquajet.se\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aquajet.se\\\/bed\\\/uploads\\\/2021\\\/11\\\/aquajet_logo-5.png\",\"contentUrl\":\"https:\\\/\\\/aquajet.se\\\/bed\\\/uploads\\\/2021\\\/11\\\/aquajet_logo-5.png\",\"width\":262,\"height\":35,\"caption\":\"Aquajet\"},\"image\":{\"@id\":\"https:\\\/\\\/aquajet.se\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aquajet's Hydrodemolition Days 2017 - Aquajet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aquajet.se\/de\/news\/aquajets-hydrodemolition-days-2017\/","og_locale":"de_DE","og_type":"article","og_title":"Aquajet's Hydrodemolition Days 2017","og_description":"Aquajet&#8217;s Hydrodemolition Tage 5-6 von April 2017 Vielen Dank an alle, die sich die Zeit nehmen, uns bei unseren Hydrodemolition-Tagen zu begleiten! Ein herzliches Willkommen an Sie alle! Wir freuen uns, Sie hier zu haben. &nbsp; Zeitplan f\u00fcr den5. und6. April Thema: Die Umwelt Mittwoch, 5. April 12.00 Begr\u00fc\u00dfung und Mittagessen im Aquajet 13.00 [&hellip;]","og_url":"https:\/\/aquajet.se\/de\/news\/aquajets-hydrodemolition-days-2017\/","og_site_name":"Aquajet","og_image":[{"width":600,"height":600,"url":"https:\/\/aquajet.se\/bed\/uploads\/2017\/02\/aquajet_hydrodemolitiondays2017-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aquajet.se\/de\/news\/aquajets-hydrodemolition-days-2017\/","url":"https:\/\/aquajet.se\/de\/news\/aquajets-hydrodemolition-days-2017\/","name":"Aquajet's Hydrodemolition Days 2017 - Aquajet","isPartOf":{"@id":"https:\/\/aquajet.se\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aquajet.se\/de\/news\/aquajets-hydrodemolition-days-2017\/#primaryimage"},"image":{"@id":"https:\/\/aquajet.se\/de\/news\/aquajets-hydrodemolition-days-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/aquajet.se\/bed\/uploads\/2017\/02\/aquajet_hydrodemolitiondays2017-1.jpg","datePublished":"2017-02-06T13:53:58+00:00","breadcrumb":{"@id":"https:\/\/aquajet.se\/de\/news\/aquajets-hydrodemolition-days-2017\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aquajet.se\/de\/news\/aquajets-hydrodemolition-days-2017\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/aquajet.se\/de\/news\/aquajets-hydrodemolition-days-2017\/#primaryimage","url":"https:\/\/aquajet.se\/bed\/uploads\/2017\/02\/aquajet_hydrodemolitiondays2017-1.jpg","contentUrl":"https:\/\/aquajet.se\/bed\/uploads\/2017\/02\/aquajet_hydrodemolitiondays2017-1.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/aquajet.se\/de\/news\/aquajets-hydrodemolition-days-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/aquajet.se\/de\/welcome-to-the-future-of-cutting-edge-hydrodemolition\/"},{"@type":"ListItem","position":2,"name":"Aquajet Nachrichten","item":"https:\/\/aquajet.se\/de\/news\/"},{"@type":"ListItem","position":3,"name":"Aquajet&#8217;s Hydrodemolition Days 2017"}]},{"@type":"WebSite","@id":"https:\/\/aquajet.se\/de\/#website","url":"https:\/\/aquajet.se\/de\/","name":"Aquajet","description":"Proven Hydrodemolition Equipment","publisher":{"@id":"https:\/\/aquajet.se\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aquajet.se\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/aquajet.se\/de\/#organization","name":"Aquajet","url":"https:\/\/aquajet.se\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/aquajet.se\/de\/#\/schema\/logo\/image\/","url":"https:\/\/aquajet.se\/bed\/uploads\/2021\/11\/aquajet_logo-5.png","contentUrl":"https:\/\/aquajet.se\/bed\/uploads\/2021\/11\/aquajet_logo-5.png","width":262,"height":35,"caption":"Aquajet"},"image":{"@id":"https:\/\/aquajet.se\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aquajet.se\/de\/wp-json\/wp\/v2\/news\/42615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aquajet.se\/de\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/aquajet.se\/de\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aquajet.se\/de\/wp-json\/wp\/v2\/media\/19544"}],"wp:attachment":[{"href":"https:\/\/aquajet.se\/de\/wp-json\/wp\/v2\/media?parent=42615"}],"wp:term":[{"taxonomy":"news_type","embeddable":true,"href":"https:\/\/aquajet.se\/de\/wp-json\/wp\/v2\/news_type?post=42615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}